{"id":223,"date":"2021-07-30T16:56:16","date_gmt":"2021-07-30T19:56:16","guid":{"rendered":"https:\/\/archiv.ar\/website\/?page_id=223"},"modified":"2021-07-30T16:56:18","modified_gmt":"2021-07-30T19:56:18","slug":"beneficios","status":"publish","type":"page","link":"https:\/\/filesa.com.ar\/website\/beneficios\/","title":{"rendered":"Beneficios"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le proponemos para su archivo<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A) Reducir costos actuales<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Afectando los recursos humanos a actividades espec\u00edficas de su organizaci\u00f3n.<\/li><li>Liberando espacios actualmente ocupados por archivos.<\/li><li>Agilizando los tiempos de b\u00fasqueda de documentaci\u00f3n.<\/li><li>Evitando problemas legales por falta de respuesta en tiempo y forma a las requisitorias oficiales.<\/li><li>Reportes del sistema inform\u00e1tico, de documentaci\u00f3n vencida de acuerdo a leyes vigentes, para su posterior baja.<\/li><li>Transformando los costos fijos en variables.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>B) Disponer en forma inmediata de su documentaci\u00f3n mediante:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ordenamiento param\u00e9trico y b\u00fasqueda sistematizada.<\/li><li>Identificaci\u00f3n individual de documentos y\/o legajos, mediante lectura \u00f3ptica de c\u00f3digos de barra.<\/li><li>Ubicaci\u00f3n estrat\u00e9gica de nuestra empresa.<\/li><li>Servicio de transporte y cadeter\u00eda permanente.<\/li><li>Asistencia alternativa por internet.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C) M\u00e1xima seguridad y confidencialidad en la gesti\u00f3n con:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sistema propio SAAR (Sistema de Administraci\u00f3n de Archivos)<\/li><li>Servidores de \u00faltima generaci\u00f3n con sistema optimizada de base de datos.<\/li><li>Licencia legales para el uso de nuestros sistemas inform\u00e1ticos.<\/li><li>Redes de estaciones de trabajo certificadas de acuerdo a Normas Internacionales.<\/li><li>Instalaciones especialmente acondicionadas con los mas modernos sistemas de alarmas.<\/li><li>Cajas normalizadas de alta resistencia, con cierres de  seguridad e identificaci\u00f3n con c\u00f3digos de barras.<\/li><li>Monitoreo edilicio permanente de polic\u00eda y bomberos, con guardia de seguridad nocturna.<\/li><li>Reporte peri\u00f3dico de documentaci\u00f3n consultada en tr\u00e1nsito.<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le proponemos para su archivo A) Reducir costos actuales Afectando los recursos humanos a actividades espec\u00edficas de su organizaci\u00f3n. Liberando espacios actualmente ocupados por archivos. Agilizando los tiempos de b\u00fasqueda de documentaci\u00f3n. Evitando problemas legales por falta de respuesta en tiempo y forma a las requisitorias oficiales. Reportes del sistema inform\u00e1tico, de documentaci\u00f3n vencida de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-223","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/pages\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":1,"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/pages\/223\/revisions"}],"predecessor-version":[{"id":224,"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/pages\/223\/revisions\/224"}],"wp:attachment":[{"href":"https:\/\/filesa.com.ar\/website\/wp-json\/wp\/v2\/media?parent=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}